{"id":15908,"date":"2023-09-22T15:26:19","date_gmt":"2023-09-22T19:26:19","guid":{"rendered":"https:\/\/notes.math.ca\/article\/nobles-gens-et-gentes-dames-quelquun-parmi-vous-se-souvient-il-de-feu-lord-buckley\/"},"modified":"2023-09-22T15:26:31","modified_gmt":"2023-09-22T19:26:31","slug":"nobles-gens-et-gentes-dames-quelquun-parmi-vous-se-souvient-il-de-feu-lord-buckley","status":"publish","type":"article","link":"https:\/\/notes.math.ca\/fr\/article\/nobles-gens-et-gentes-dames-quelquun-parmi-vous-se-souvient-il-de-feu-lord-buckley\/","title":{"rendered":"Nobles gens et gentes dames, quelqu\u2019un parmi vous se souvient-il de feu Lord Buckley?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le type faisait son num\u00e9ro pile au c\u0153ur du si\u00e8cle qu\u2019on obtient par dix fois deux, dans un accent aussi authentique qu\u2019un billet de trois dollars et un vocabulaire qu\u2019il avait emprunt\u00e9 quelque part \u00e0 Harlem et qu\u2019il avait oubli\u00e9 de rendre au propri\u00e9taire. Et c\u2019\u00e9tait le gars le plus branch\u00e9, le plus ol\u00e9 ol\u00e9, le plus tordant que vous pouvez imaginer. Si vous ne savez pas de qui je parle, mettez cet \u00e9dito de c\u00f4t\u00e9 et allez faire votre culture sur Internet. J\u2019ai tout mon temps. <\/p>\n\n<p class=\"wp-block-paragraph\">Joan Baez n\u2019\u00e9tait qu\u2019une jeune gazelle quand elle lui a d\u00e9di\u00e9 un mot sur la couverture de son album; et, coquins et coquines, laissez-moi vous dire, y a pas plus grand honneur qu\u2019un salamalec sur un album de Baez. C\u2019est ce que le Spiderman, notre Spider Robinson bien canadien, r\u00e9p\u00e9tait \u00e0 tout vent alors que \u00ab le Nazz \u00bb (alors, vous l\u2019avez faite, cette recherche?) n\u2019\u00e9tait encore que charpentier.<\/p>\n\n<p class=\"wp-block-paragraph\">Allons donc, pensez-vous s\u00fbrement, est-ce que cet \u00e9dito perdrait les p\u00e9dales? Pourquoi (si ce n\u2019est par pure envie face au seul comique qui pouvait vraiment faire sauter la baraque), pourquoi plagier feu Lord Buckley? Eh bien, parce que nous voil\u00e0 en d\u00e9but de session, et que j\u2019ai devant moi un jeune public tout frais, et que je savoure \u00e0 nouveau le d\u00e9lice \u2013 et le pouvoir, oui, monsieur! \u2013 de faire le cabotin devant la classe. Non pas parce que la mati\u00e8re (alg\u00e8bre g\u00e9n\u00e9rale) endort l\u2019auditoire\u00a0: rien ne serait plus loin de la v\u00e9rit\u00e9. Mais parce que je crois fermement qu\u2019un cours magistral auquel on ajoute quelques \u00e9pices \u2013 de votre propre cru, il va sans dire \u2013 sera mieux retenu que \u00ab\u00a0les faits, ma p\u2019tite dame, simplement les faits.\u00a0\u00bb<\/p>\n\n<p class=\"wp-block-paragraph\">Je ne vous demande pas de jongler avec les marqueurs ou de faire des rimettes rigolotes sur les c\u00e9l\u00e8bres intellects qui ont prouv\u00e9 vos th\u00e9or\u00e8mes. Mais pensez \u00e0 votre dernier congr\u00e8s. De quels conf\u00e9renciers vous souvenez-vous? \u00c9tait-ce le jeune coll\u00e8gue nerveux vous servant un discours aussi savoureux qu\u2019un plat sans sel et qui remportera la m\u00e9daille Fields dans quelques ann\u00e9es? Je parie plut\u00f4t que les expos\u00e9s qui vous restent en t\u00eate portaient sur un sujet int\u00e9ressant piment\u00e9 d\u2019un peu d\u2019humour. <\/p>\n\n<p class=\"wp-block-paragraph\">Bref, il n\u2019y a pas que le contenu qui compte, il y a la mani\u00e8re. Alors, nobles gens et gentes dames, retournez en classe et impressionnez la galerie!<\/p>\n","protected":false},"author":11,"template":"","section":[23],"keyword":[387],"class_list":["post-15908","article","type-article","status-publish","hentry","section-editorial-2","keyword-redacteurs-fr"],"toolset-meta":{"author-4-info":{"author-4-surname":{"type":"textfield","raw":""},"author-4-given-names":{"type":"textfield","raw":""},"author-4-honorific":{"type":"textfield","raw":""},"author-4-institution":{"type":"textfield","raw":""},"author-4-email":{"type":"email","raw":""},"author-4-cms-role":{"type":"textfield","raw":""}},"author-3-info":{"author-3-surname":{"type":"textfield","raw":""},"author-3-given-names":{"type":"textfield","raw":""},"author-3-honorific":{"type":"textfield","raw":""},"author-3-institution":{"type":"textfield","raw":""},"author-3-email":{"type":"email","raw":""},"author-3-cms-role":{"type":"textfield","raw":""}},"author-2-info":{"author-2-surname":{"type":"textfield","raw":""},"author-2-given-names":{"type":"textfield","raw":""},"author-2-honorific":{"type":"textfield","raw":""},"author-2-institution":{"type":"textfield","raw":""},"author-2-email":{"type":"email","raw":""},"author-2-cms-role":{"type":"textfield","raw":""}},"author-info":{"author-surname":{"type":"textfield","raw":"Dawson"},"author-given-names":{"type":"textfield","raw":"Robert"},"author-honorific":{"type":"textfield","raw":"Professor"},"author-email":{"type":"email","raw":"rjmdawson@gmail.com"},"author-institution":{"type":"textfield","raw":"Saint Mary's University"},"author-cms-role":{"type":"textfield","raw":"Editor-in-Chief, CMS Notes"}},"unknown":{"downloadable-pdf":{"type":"file","raw":"","attachment_id":null},"article-toc-weight":{"type":"numeric","raw":"2"},"author-surname":{"type":"textfield","raw":"Dawson"},"author-given-names":{"type":"textfield","raw":"Robert"}}},"_links":{"self":[{"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/article\/15908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":3,"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/article\/15908\/revisions"}],"predecessor-version":[{"id":15911,"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/article\/15908\/revisions\/15911"}],"wp:attachment":[{"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/media?parent=15908"}],"wp:term":[{"taxonomy":"section","embeddable":true,"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/section?post=15908"},{"taxonomy":"keyword","embeddable":true,"href":"https:\/\/notes.math.ca\/fr\/wp-json\/wp\/v2\/keyword?post=15908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}